{"id":78,"count":1,"description":"","link":"https:\/\/nuclicdigitalservices.com\/index.php\/category\/website-development\/","name":"Website Development","slug":"website-development","taxonomy":"category","parent":0,"meta":[],"acf":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/nuclicdigitalservices.com\/index.php\/category\/website-development\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/78\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nuclicdigitalservices.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/index.php\\\/category\\\/website-development\\\/#listItem\",\"name\":\"Website Development\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/index.php\\\/category\\\/website-development\\\/#listItem\",\"position\":2,\"name\":\"Website Development\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/78\\\/#collectionpage\",\"url\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/78\\\/\",\"name\":\"Website Development - Nuclic Digital Services\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/78\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/#organization\",\"name\":\"Marketing Agency\",\"url\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/#website\",\"url\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/\",\"name\":\"Marketing Agency\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/nuclicdigitalservices.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Website Development - Nuclic Digital Services","description":"","canonical_url":"https:\/\/nuclicdigitalservices.com\/index.php\/category\/website-development\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/nuclicdigitalservices.com\/wp-json\/wp\/v2\/categories\/78\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nuclicdigitalservices.com#listItem","position":1,"name":"Home","item":"https:\/\/nuclicdigitalservices.com","nextItem":{"@type":"ListItem","@id":"https:\/\/nuclicdigitalservices.com\/index.php\/category\/website-development\/#listItem","name":"Website Development"}},{"@type":"ListItem","@id":"https:\/\/nuclicdigitalservices.com\/index.php\/category\/website-development\/#listItem","position":2,"name":"Website Development","previousItem":{"@type":"ListItem","@id":"https:\/\/nuclicdigitalservices.com#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/nuclicdigitalservices.com\/wp-json\/wp\/v2\/categories\/78\/#collectionpage","url":"https:\/\/nuclicdigitalservices.com\/wp-json\/wp\/v2\/categories\/78\/","name":"Website Development - Nuclic Digital Services","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/nuclicdigitalservices.com\/#website"},"breadcrumb":{"@id":"https:\/\/nuclicdigitalservices.com\/wp-json\/wp\/v2\/categories\/78\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/nuclicdigitalservices.com\/#organization","name":"Marketing Agency","url":"https:\/\/nuclicdigitalservices.com\/"},{"@type":"WebSite","@id":"https:\/\/nuclicdigitalservices.com\/#website","url":"https:\/\/nuclicdigitalservices.com\/","name":"Marketing Agency","inLanguage":"en-US","publisher":{"@id":"https:\/\/nuclicdigitalservices.com\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/nuclicdigitalservices.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWebsite Development\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nuclicdigitalservices.com"},{"label":"Website Development","link":"https:\/\/nuclicdigitalservices.com\/index.php\/category\/website-development\/"}],"_links":{"self":[{"href":"https:\/\/nuclicdigitalservices.com\/index.php\/wp-json\/wp\/v2\/categories\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuclicdigitalservices.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/nuclicdigitalservices.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/nuclicdigitalservices.com\/index.php\/wp-json\/wp\/v2\/posts?categories=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}